{"id":1220,"date":"2022-04-13T22:30:44","date_gmt":"2022-04-13T20:30:44","guid":{"rendered":"https:\/\/zielonedomki.pl\/?page_id=1220"},"modified":"2022-04-13T22:40:53","modified_gmt":"2022-04-13T20:40:53","slug":"o-domkach-2","status":"publish","type":"page","link":"https:\/\/zielonedomki.pl\/index.php\/o-domkach-2\/","title":{"rendered":"o domkach"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1220\" class=\"elementor elementor-1220\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9505247 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"9505247\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fc3492\" data-id=\"7fc3492\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acda82a elementor-widget elementor-widget-heading\" data-id=\"acda82a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">o domkach<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8bdb336 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8bdb336\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b59a44c animated-slow\" data-id=\"b59a44c\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2d2068 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2d2068\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2fbb8d3\" data-id=\"2fbb8d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9882a31 elementor-widget elementor-widget-eael-creative-button\" data-id=\"9882a31\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default\" href=\"https:\/\/zielonedomki.pl\/index.php\/o-domkach\/\" data-text=\"\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                    \n                    <span class=\"cretive-button-text\">og\u00f3lne<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2482c21\" data-id=\"2482c21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89677e4 elementor-widget elementor-widget-eael-creative-button\" data-id=\"89677e4\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default\" href=\"https:\/\/zielonedomki.pl\/index.php\/wyposazenie\/\" data-text=\"\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                    \n                    <span class=\"cretive-button-text\">wyposa\u017cenie<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb4780d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb4780d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b52c88f\" data-id=\"b52c88f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30e525f elementor-widget elementor-widget-eael-creative-button\" data-id=\"30e525f\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default\" href=\"https:\/\/zielonedomki.pl\/index.php\/promocje-2\/\" data-text=\"\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                    \n                    <span class=\"cretive-button-text\">atrakcje<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30340ce\" data-id=\"30340ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdc9a09 elementor-widget elementor-widget-eael-creative-button\" data-id=\"fdc9a09\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default\" href=\"https:\/\/zielonedomki.pl\/index.php\/faq\/\" data-text=\"\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                    \n                    <span class=\"cretive-button-text\">FAQ<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>o domkach og\u00f3lne wyposa\u017cenie atrakcje FAQ<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1220","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/zielonedomki.pl\/index.php\/wp-json\/wp\/v2\/pages\/1220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zielonedomki.pl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zielonedomki.pl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zielonedomki.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zielonedomki.pl\/index.php\/wp-json\/wp\/v2\/comments?post=1220"}],"version-history":[{"count":24,"href":"https:\/\/zielonedomki.pl\/index.php\/wp-json\/wp\/v2\/pages\/1220\/revisions"}],"predecessor-version":[{"id":1246,"href":"https:\/\/zielonedomki.pl\/index.php\/wp-json\/wp\/v2\/pages\/1220\/revisions\/1246"}],"wp:attachment":[{"href":"https:\/\/zielonedomki.pl\/index.php\/wp-json\/wp\/v2\/media?parent=1220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}